{"id":20639,"date":"2024-08-13T07:00:38","date_gmt":"2024-08-13T05:00:38","guid":{"rendered":"https:\/\/butgenbach.info\/walking\/schwarz-trailrun-buetgenbach\/"},"modified":"2025-12-09T13:25:08","modified_gmt":"2025-12-09T12:25:08","slug":"zwart-trailrun-buetgenbach","status":"publish","type":"walking","link":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/","title":{"rendered":"ZWART Trailrun B\u00fctgenbach"},"featured_media":0,"menu_order":32,"template":"","walking-type":[170],"tags":[],"class_list":["post-20639","walking","type-walking","status-publish","hentry","walking-type-trailrunning-nl"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZWART Trailrun B\u00fctgenbach - B\u00fctgenbach Tourist Info<\/title>\n<meta name=\"description\" content=\"Rustige looproute van 38 kilometer met enkele uitdagende trails in de gemeente B\u00fctgenbach\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZWART Trailrun B\u00fctgenbach - B\u00fctgenbach Tourist Info\" \/>\n<meta property=\"og:description\" content=\"Rustige looproute van 38 kilometer met enkele uitdagende trails in de gemeente B\u00fctgenbach\" \/>\n<meta property=\"og:url\" content=\"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/\" \/>\n<meta property=\"og:site_name\" content=\"B\u00fctgenbach Tourist Info\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-09T12:25:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/wandelen\\\/zwart-trailrun-buetgenbach\\\/\",\"url\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/wandelen\\\/zwart-trailrun-buetgenbach\\\/\",\"name\":\"ZWART Trailrun B\u00fctgenbach - B\u00fctgenbach Tourist Info\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#website\"},\"datePublished\":\"2024-08-13T05:00:38+00:00\",\"dateModified\":\"2025-12-09T12:25:08+00:00\",\"description\":\"Rustige looproute van 38 kilometer met enkele uitdagende trails in de gemeente B\u00fctgenbach\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/wandelen\\\/zwart-trailrun-buetgenbach\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/butgenbach.info\\\/nl\\\/wandelen\\\/zwart-trailrun-buetgenbach\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/wandelen\\\/zwart-trailrun-buetgenbach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wandelen\",\"item\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/wandelen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ZWART Trailrun B\u00fctgenbach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/\",\"name\":\"B\u00fctgenbach Tourist Info\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZWART Trailrun B\u00fctgenbach - B\u00fctgenbach Tourist Info","description":"Rustige looproute van 38 kilometer met enkele uitdagende trails in de gemeente B\u00fctgenbach","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/","og_locale":"nl_NL","og_type":"article","og_title":"ZWART Trailrun B\u00fctgenbach - B\u00fctgenbach Tourist Info","og_description":"Rustige looproute van 38 kilometer met enkele uitdagende trails in de gemeente B\u00fctgenbach","og_url":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/","og_site_name":"B\u00fctgenbach Tourist Info","article_modified_time":"2025-12-09T12:25:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/","url":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/","name":"ZWART Trailrun B\u00fctgenbach - B\u00fctgenbach Tourist Info","isPartOf":{"@id":"https:\/\/butgenbach.info\/nl\/#website"},"datePublished":"2024-08-13T05:00:38+00:00","dateModified":"2025-12-09T12:25:08+00:00","description":"Rustige looproute van 38 kilometer met enkele uitdagende trails in de gemeente B\u00fctgenbach","breadcrumb":{"@id":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/butgenbach.info\/nl\/wandelen\/zwart-trailrun-buetgenbach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/butgenbach.info\/nl\/"},{"@type":"ListItem","position":2,"name":"Wandelen","item":"https:\/\/butgenbach.info\/nl\/wandelen\/"},{"@type":"ListItem","position":3,"name":"ZWART Trailrun B\u00fctgenbach"}]},{"@type":"WebSite","@id":"https:\/\/butgenbach.info\/nl\/#website","url":"https:\/\/butgenbach.info\/nl\/","name":"B\u00fctgenbach Tourist Info","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/butgenbach.info\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"}]}},"_links":{"self":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/walking\/20639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/walking"}],"about":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/types\/walking"}],"wp:attachment":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/media?parent=20639"}],"wp:term":[{"taxonomy":"walking-type","embeddable":true,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/walking-type?post=20639"},{"taxonomy":"tags","embeddable":true,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/tags?post=20639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}