{"id":22605,"date":"2025-11-29T11:18:46","date_gmt":"2025-11-29T10:18:46","guid":{"rendered":"https:\/\/butgenbach.info\/weihnachtszauber-in-der-region-buetgenbach-die-schoensten-maerkte-und-events\/"},"modified":"2025-12-05T09:50:04","modified_gmt":"2025-12-05T08:50:04","slug":"kerstmarkten-en-lichtevents-in-en-rond-buetgenbach","status":"publish","type":"post","link":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/","title":{"rendered":"Kerstmarkten en lichtevents in en rond B\u00fctgenbach"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"xn-wppe-expiration":[],"xn-wppe-expiration-action":[],"xn-wppe-expiration-prefix":[],"footnotes":""},"categories":[10],"tags":[],"class_list":["post-22605","post","type-post","status-publish","format-standard","hentry","category-geen-onderdeel-van-een-categorie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728<\/title>\n<meta name=\"description\" content=\"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728\" \/>\n<meta property=\"og:description\" content=\"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/\" \/>\n<meta property=\"og:site_name\" content=\"B\u00fctgenbach Tourist Info\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-29T10:18:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-05T08:50:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/butgenbach.info\/wp-content\/uploads\/2024\/11\/Monschau-1-e1764922543114.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1125\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"An Maria Van Rie\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728\" \/>\n<meta name=\"twitter:description\" content=\"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/butgenbach.info\/wp-content\/uploads\/2024\/11\/Monschau-1-e1764922543114.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"An Maria Van Rie\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/\"},\"author\":{\"name\":\"An Maria Van Rie\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#\\\/schema\\\/person\\\/6b60facacedf2a928792e9bfd8f1654f\"},\"headline\":\"Kerstmarkten en lichtevents in en rond B\u00fctgenbach\",\"datePublished\":\"2025-11-29T10:18:46+00:00\",\"dateModified\":\"2025-12-05T08:50:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/\"},\"wordCount\":8,\"articleSection\":[\"Geen onderdeel van een categorie\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/\",\"url\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/\",\"name\":\"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#website\"},\"datePublished\":\"2025-11-29T10:18:46+00:00\",\"dateModified\":\"2025-12-05T08:50:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#\\\/schema\\\/person\\\/6b60facacedf2a928792e9bfd8f1654f\"},\"description\":\"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kerstmarkten en lichtevents in en rond B\u00fctgenbach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/\",\"name\":\"B\u00fctgenbach Tourist Info\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/#\\\/schema\\\/person\\\/6b60facacedf2a928792e9bfd8f1654f\",\"name\":\"An Maria Van Rie\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b9dd5c165bf50b764a1f04d85adf971a72480c9036337e51492e3b101c0949c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b9dd5c165bf50b764a1f04d85adf971a72480c9036337e51492e3b101c0949c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0b9dd5c165bf50b764a1f04d85adf971a72480c9036337e51492e3b101c0949c?s=96&d=mm&r=g\",\"caption\":\"An Maria Van Rie\"},\"url\":\"https:\\\/\\\/butgenbach.info\\\/nl\\\/author\\\/avrie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728","description":"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/","og_locale":"nl_NL","og_type":"article","og_title":"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728","og_description":"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.","og_url":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/","og_site_name":"B\u00fctgenbach Tourist Info","article_published_time":"2025-11-29T10:18:46+00:00","article_modified_time":"2025-12-05T08:50:04+00:00","og_image":[{"width":1125,"height":1500,"url":"https:\/\/butgenbach.info\/wp-content\/uploads\/2024\/11\/Monschau-1-e1764922543114.jpg","type":"image\/jpeg"}],"author":"An Maria Van Rie","twitter_card":"summary_large_image","twitter_title":"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728","twitter_description":"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.","twitter_image":"https:\/\/butgenbach.info\/wp-content\/uploads\/2024\/11\/Monschau-1-e1764922543114.jpg","twitter_misc":{"Geschreven door":"An Maria Van Rie"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/#article","isPartOf":{"@id":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/"},"author":{"name":"An Maria Van Rie","@id":"https:\/\/butgenbach.info\/nl\/#\/schema\/person\/6b60facacedf2a928792e9bfd8f1654f"},"headline":"Kerstmarkten en lichtevents in en rond B\u00fctgenbach","datePublished":"2025-11-29T10:18:46+00:00","dateModified":"2025-12-05T08:50:04+00:00","mainEntityOfPage":{"@id":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/"},"wordCount":8,"articleSection":["Geen onderdeel van een categorie"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/","url":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/","name":"Kerstmarkten en lichtevents in de omgeving van B\u00fctgenbach \u2728","isPartOf":{"@id":"https:\/\/butgenbach.info\/nl\/#website"},"datePublished":"2025-11-29T10:18:46+00:00","dateModified":"2025-12-05T08:50:04+00:00","author":{"@id":"https:\/\/butgenbach.info\/nl\/#\/schema\/person\/6b60facacedf2a928792e9bfd8f1654f"},"description":"Alle kerstmarkten en lichtevents in de buurt van B\u00fctgenbach \u2013 op minder dan 30 minuten rijden. Data, hoogtepunten en idee\u00ebn voor uitstapjes.","breadcrumb":{"@id":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/butgenbach.info\/nl\/kerstmarkten-en-lichtevents-in-en-rond-buetgenbach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/butgenbach.info\/nl\/"},{"@type":"ListItem","position":2,"name":"Kerstmarkten en lichtevents in en rond B\u00fctgenbach"}]},{"@type":"WebSite","@id":"https:\/\/butgenbach.info\/nl\/#website","url":"https:\/\/butgenbach.info\/nl\/","name":"B\u00fctgenbach Tourist Info","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/butgenbach.info\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/butgenbach.info\/nl\/#\/schema\/person\/6b60facacedf2a928792e9bfd8f1654f","name":"An Maria Van Rie","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/0b9dd5c165bf50b764a1f04d85adf971a72480c9036337e51492e3b101c0949c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0b9dd5c165bf50b764a1f04d85adf971a72480c9036337e51492e3b101c0949c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0b9dd5c165bf50b764a1f04d85adf971a72480c9036337e51492e3b101c0949c?s=96&d=mm&r=g","caption":"An Maria Van Rie"},"url":"https:\/\/butgenbach.info\/nl\/author\/avrie\/"}]}},"_links":{"self":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/posts\/22605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/comments?post=22605"}],"version-history":[{"count":10,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/posts\/22605\/revisions"}],"predecessor-version":[{"id":28222,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/posts\/22605\/revisions\/28222"}],"wp:attachment":[{"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/media?parent=22605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/categories?post=22605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/butgenbach.info\/nl\/wp-json\/wp\/v2\/tags?post=22605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}